{"id":32960,"date":"2021-08-15T11:00:00","date_gmt":"2021-08-15T09:00:00","guid":{"rendered":"https:\/\/lotsdenadal.cat\/?p=32960"},"modified":"2026-01-09T15:11:30","modified_gmt":"2026-01-09T14:11:30","slug":"cursa-infantil-adaptada","status":"publish","type":"post","link":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/","title":{"rendered":"Carrera infantil adaptada"},"content":{"rendered":"\n<h1>Una carrera infantil adaptada<\/h1>\n<p>Hay ideas que nacen con un papelito enganchado donde hay escrito \u201cNo s\u00e9 si crecer\u00e9, pero lo intentar\u00e9 con fuerza\u201d. Y, a veces, estas ideas se acaban convirtiendo en aventuras gigantes. C\u00f3mo estaban destinadas a ser. Como la iniciativa de Noem\u00ed Font, la madre de Emma, una ni\u00f1a con <a href=\"https:\/\/espinabifida.cat\/espina\/\" target=\"_blank\" rel=\"noopener\">espina b\u00edfida<\/a>, que decidi\u00f3 canalizar las ganas de correr de su hija y promover una Carrera infantil adaptada para ni\u00f1os con movilidad reducida.<\/p>\n<p>Ya os lo imagin\u00e1is, \u00bfverdad? \u00a1Lo hizo realidad!<\/p>\n<p>La carrera se celebr\u00f3 el pasado s\u00e1bado, 14 de agosto, en el marco de las <a href=\"https:\/\/www.barcelona.cat\/culturapopular\/ca\/festes-i-tradicions\/festes-de-sant-roc-de-la-placa-nova\" target=\"_blank\" rel=\"noopener\">Festes de Sant Roc<\/a> del Barri G\u00f2tic de Barcelona. Los participantes pod\u00edan elegir, en funci\u00f3n de sus capacidades, la longitud del recorrido, 10, 20 o un m\u00e1ximo de 30 metros. Y empez\u00f3 a las 10 de la ma\u00f1ana en la <a href=\"https:\/\/barcelona.callejero.net\/avinguda-de-la-catedral.html\" target=\"_blank\" rel=\"noopener\">Avinguda de la Catedral de Barcelona<\/a>.<\/p>\n\n\t<section class=\"section\" id=\"section_1784347841\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-center row-divided\"  id=\"row-1034946950\">\n\n\n\t<div id=\"col-655062490\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"ca\">Punys apretats, cos en tensi\u00f3, mirada atenta, boca tancada i en el meu cap: \u00abfilla, posa b\u00e9 els peus, no et facis mal, no corris tant, v\u00e9s amb compte, que la gent s&#8217;aparti&#8230;\u00bb<br \/>I em diu:<br \/>_ Mama va, fem una cursa!<br \/>_ Som-hi! <a href=\"https:\/\/t.co\/2DyjjAKXpS\">pic.twitter.com\/2DyjjAKXpS<\/a><\/p>\n<p>\u2014 Noem\u00ed Font (@ratolinaemma) <a href=\"https:\/\/twitter.com\/ratolinaemma\/status\/1385968433838313474?ref_src=twsrc%5Etfw\">April 24, 2021<\/a><\/p>\n<\/blockquote>\n<p> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1998354568\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><em>\u201cPu\u00f1os apretados, cuerpo en tensi\u00f3n, mirada atenta, boca cerrada y en mi cabeza: \u201chija, pon bien los pies, no te hagas da\u00f1o, no corras tanto, ve con cuidado, que la gente se aparte&#8230;\u201d<\/em><br \/><em>Y me dice:<\/em><br \/><em>_Mama va, \u00a1hacemos una carrera!<\/em><br \/><em>_\u00a1Venga!\u201d<\/em><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1034946950 > .col > .col-inner {\n  padding: 0px 0px 9px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1764304889\">\n\n\n\t<div id=\"col-163022691\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"lead\">La fuerza de la gente<\/h2>\n<p>Noem\u00ed explic\u00f3 v\u00eda Twitter la ilusi\u00f3n que le hac\u00eda organizarlo, y que la primera empresa les hab\u00eda cerrado las puertas. Es injusto que se cierren puertas en momentos donde se tienen que dar alas. Pero, por suerte, muchas personas se abocaron completamente. La solidaridad no ha muerto, y en momentos como este es cuando queda demostrado, cuando seguimos viendo esperanza en la sociedad. Una sociedad que se ha abocado en la hora de participar y ayudar. Una sociedad de la cual estamos orgullosos de formar parte.<\/p>\n<p>Y a partir de all\u00ed fue una avalancha de propuestas, de implicaci\u00f3n, mucha gente con ganas de participar. \u00bfQue se tiene que montar una carrera? \u00a1Pues montamos una carrera infantil adaptada! T\u00fa llevas los premios, yo los dorsales, yo imprimo camisetas, t\u00fa llevas la bebida, yo har\u00e9 de <em>speaker<\/em>, t\u00fa vigila que a nadie le falte agua&#8230; Y as\u00ed llegamos a un s\u00e1bado de verano a las 10 de la ma\u00f1ana con la aportaci\u00f3n de muchos, con la suma de todos. Con la fuerza de la gente.<\/p>\n<p>La primera carrera infantil adaptada del barrio G\u00f2tic se hab\u00eda hecho realidad.<\/p>\n<h2>Todos campeones<\/h2>\n<p>Por nuestra parte, desde <a href=\"https:\/\/lotsdenadal.cat\/es\/quienes-somos\/\" target=\"_blank\" rel=\"noopener\">Harcogourmet<\/a> tambi\u00e9n quisimos aportar nuestro grano de arena. Bien, m\u00e1s que grano, una cesta. Adaptamos una cesta de Navidad para que fuera como la bolsa de alimentos y de recuerdo que se da al acabar una carrera. Un lote para cada participante con productos para que pudieran hacer un aperitivo y que el d\u00eda todav\u00eda fuera m\u00e1s redondo.<\/p>\n<p>Se trataba de un premio para todos los participantes y para poderlo compartir con sus familias, naturalmente. Porque todos son unos campeones. De la carrera. De la vida. De la superaci\u00f3n d\u00eda tras d\u00eda. De mirar los obst\u00e1culos con una sonrisa diciendo: \u201cYo puedo, yo soy capaz.\u201d A veces no se ve todo el esfuerzo y la superaci\u00f3n que hay detr\u00e1s, pero la clave est\u00e1 en no rendirse. As\u00ed que enhorabuena a todos los ni\u00f1os que nos dieron una lecci\u00f3n de vida.<\/p>\n<h3 class=\"lead\">M\u00e1s eventos inclusivos en camino<\/h3>\n<p>Todav\u00eda con los ojos negados de l\u00e1grimas&#8230; cu\u00e1nta emoci\u00f3n, cu\u00e1nta superaci\u00f3n. Que especial lo que vivimos el s\u00e1bado. Por eso hoy quer\u00edamos hablar de ello en nuestro blog, para compartirlo, por qu\u00e9 esta iniciativa no parece tener un final. Noem\u00ed puso en marcha un motor que ha llegado a calentar muchos corazones. Y una llama colectiva no se apaga nunca.<\/p>\n<p>Por otro lado, la sociedad se ha movido tanto que ya se han programado otra carrera infantil adaptada. En concreto dos carreras m\u00e1s de momento. Una en octubre, en las <a href=\"https:\/\/www.barcelona.cat\/culturapopular\/ca\/festes-i-tradicions\/festa-major-de-lesquerra-de-leixample\" target=\"_blank\" rel=\"noopener\">Festes de l\u2019Eixample Esquerre<\/a>, y otra en diciembre, por las <a href=\"http:\/\/www.festessantandreu.cat\/\" target=\"_blank\" rel=\"noopener\">Festes de Sant Andreu<\/a>. Es esencial plantearles a los ni\u00f1os retos que puedan lograr, pero que a la vez les hagan crecer, so\u00f1ar, superarse.<\/p>\n<p>\u00a1Salud!<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_752680296\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_752680296 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1764304889 > .col > .col-inner {\n  padding: 15px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1784347841 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"<p>Hay ideas que acaban convirti\u00e9ndose en aventuras gigantes.<\/p>\n","protected":false},"author":1,"featured_media":5000801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[63,77],"tags":[],"class_list":["post-32960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones-es","category-publicacions-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carrera infantil adaptada | Lotes de Navidad<\/title>\n<meta name=\"description\" content=\"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrera infantil adaptada\" \/>\n<meta property=\"og:description\" content=\"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/\" \/>\n<meta property=\"og:site_name\" content=\"Lotes de Navidad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/harcogourmet\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-15T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T14:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equip d&#039;Harcogourmet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@harcogourmet\" \/>\n<meta name=\"twitter:site\" content=\"@harcogourmet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equip d&#039;Harcogourmet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/\"},\"author\":{\"name\":\"Equip d'Harcogourmet\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#\\\/schema\\\/person\\\/7b669d90a836c1006f233013477b6ae1\"},\"headline\":\"Carrera infantil adaptada\",\"datePublished\":\"2021-08-15T09:00:00+00:00\",\"dateModified\":\"2026-01-09T14:11:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/\"},\"wordCount\":794,\"publisher\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cursa-infantil-adaptada.jpg\",\"articleSection\":[\"Publicaciones\",\"Publicacions\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/\",\"url\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/\",\"name\":\"Carrera infantil adaptada | Lotes de Navidad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cursa-infantil-adaptada.jpg\",\"datePublished\":\"2021-08-15T09:00:00+00:00\",\"dateModified\":\"2026-01-09T14:11:30+00:00\",\"description\":\"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cursa-infantil-adaptada.jpg\",\"contentUrl\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cursa-infantil-adaptada.jpg\",\"width\":800,\"height\":567,\"caption\":\"Carrera infantil adaptada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/cursa-infantil-adaptada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carrera infantil adaptada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/\",\"name\":\"Lots de Nadal Harcogourmet\",\"description\":\"Lotes de Navidad con productos catalanes\",\"publisher\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#organization\"},\"alternateName\":\"LN Harcogourmet\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#organization\",\"name\":\"Lotes de Navidad Harcogourmet\",\"alternateName\":\"Harcogourmet\",\"url\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HG_negre.png\",\"contentUrl\":\"https:\\\/\\\/lotsdenadal.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HG_negre.png\",\"width\":604,\"height\":108,\"caption\":\"Lotes de Navidad Harcogourmet\"},\"image\":{\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/harcogourmet\",\"https:\\\/\\\/x.com\\\/harcogourmet\",\"https:\\\/\\\/instagram.com\\\/harcogourmet\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3240347\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCoWNvGkEBJxGoCzwURxSrcQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lotsdenadal.cat\\\/es\\\/#\\\/schema\\\/person\\\/7b669d90a836c1006f233013477b6ae1\",\"name\":\"Equip d'Harcogourmet\",\"sameAs\":[\"http:\\\/\\\/lotsdenadal.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carrera infantil adaptada | Lotes de Navidad","description":"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/","og_locale":"es_ES","og_type":"article","og_title":"Carrera infantil adaptada","og_description":"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.","og_url":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/","og_site_name":"Lotes de Navidad","article_publisher":"https:\/\/facebook.com\/harcogourmet","article_published_time":"2021-08-15T09:00:00+00:00","article_modified_time":"2026-01-09T14:11:30+00:00","og_image":[{"width":800,"height":567,"url":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg","type":"image\/jpeg"}],"author":"Equip d'Harcogourmet","twitter_card":"summary_large_image","twitter_creator":"@harcogourmet","twitter_site":"@harcogourmet","twitter_misc":{"Escrito por":"Equip d'Harcogourmet","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#article","isPartOf":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/"},"author":{"name":"Equip d'Harcogourmet","@id":"https:\/\/lotsdenadal.cat\/es\/#\/schema\/person\/7b669d90a836c1006f233013477b6ae1"},"headline":"Carrera infantil adaptada","datePublished":"2021-08-15T09:00:00+00:00","dateModified":"2026-01-09T14:11:30+00:00","mainEntityOfPage":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/"},"wordCount":794,"publisher":{"@id":"https:\/\/lotsdenadal.cat\/es\/#organization"},"image":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#primaryimage"},"thumbnailUrl":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg","articleSection":["Publicaciones","Publicacions"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/","url":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/","name":"Carrera infantil adaptada | Lotes de Navidad","isPartOf":{"@id":"https:\/\/lotsdenadal.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#primaryimage"},"image":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#primaryimage"},"thumbnailUrl":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg","datePublished":"2021-08-15T09:00:00+00:00","dateModified":"2026-01-09T14:11:30+00:00","description":"Noem\u00ed, madre de Emma, una ni\u00f1a con espina b\u00edfida, que decidi\u00f3 canalizar sus ganas de correr y promover una carrera infantil adaptada.","breadcrumb":{"@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#primaryimage","url":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg","contentUrl":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2021\/08\/cursa-infantil-adaptada.jpg","width":800,"height":567,"caption":"Carrera infantil adaptada"},{"@type":"BreadcrumbList","@id":"https:\/\/lotsdenadal.cat\/es\/cursa-infantil-adaptada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/lotsdenadal.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Carrera infantil adaptada"}]},{"@type":"WebSite","@id":"https:\/\/lotsdenadal.cat\/es\/#website","url":"https:\/\/lotsdenadal.cat\/es\/","name":"Lots de Nadal Harcogourmet","description":"Lotes de Navidad con productos catalanes","publisher":{"@id":"https:\/\/lotsdenadal.cat\/es\/#organization"},"alternateName":"LN Harcogourmet","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lotsdenadal.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lotsdenadal.cat\/es\/#organization","name":"Lotes de Navidad Harcogourmet","alternateName":"Harcogourmet","url":"https:\/\/lotsdenadal.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lotsdenadal.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2023\/06\/HG_negre.png","contentUrl":"https:\/\/lotsdenadal.cat\/wp-content\/uploads\/2023\/06\/HG_negre.png","width":604,"height":108,"caption":"Lotes de Navidad Harcogourmet"},"image":{"@id":"https:\/\/lotsdenadal.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/harcogourmet","https:\/\/x.com\/harcogourmet","https:\/\/instagram.com\/harcogourmet","https:\/\/www.linkedin.com\/company\/3240347\/","https:\/\/www.youtube.com\/channel\/UCoWNvGkEBJxGoCzwURxSrcQ"]},{"@type":"Person","@id":"https:\/\/lotsdenadal.cat\/es\/#\/schema\/person\/7b669d90a836c1006f233013477b6ae1","name":"Equip d'Harcogourmet","sameAs":["http:\/\/lotsdenadal.cat"]}]}},"_links":{"self":[{"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/posts\/32960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/comments?post=32960"}],"version-history":[{"count":0,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/posts\/32960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/media\/5000801"}],"wp:attachment":[{"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/media?parent=32960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/categories?post=32960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lotsdenadal.cat\/es\/wp-json\/wp\/v2\/tags?post=32960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}